{"id":17130,"date":"2016-09-29T08:38:11","date_gmt":"2016-09-29T06:38:11","guid":{"rendered":"https:\/\/www.nooteboom.com\/fr\/?p=17130"},"modified":"2016-09-29T08:38:31","modified_gmt":"2016-09-29T06:38:31","slug":"nouvelle-manoovr-avec-fosse-pour-bras-de-pelle","status":"publish","type":"post","link":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/","title":{"rendered":"Nouvelle Manoovr avec fosse pour bras de pelle"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<h2>Programme d\u2019expansion du Manoovr<\/h2>\n<p>La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu&rsquo;\u00e0 six essieux. D&rsquo;autres v\u00e9hicules de la g\u00e9n\u00e9ration Manoovr peuvent \u00eatre \u00e9quip\u00e9s d\u2019une fosse pour bras de pelle sur demande. La largeur de la fosse d\u00e9pend de la largeur du v\u00e9hicule. Avec un v\u00e9hicule d&rsquo;une largeur de 2 740 mm la fosse de bras de pelle est de 800 mm de large et avec une remorque qui fait 2 890 mm de large, la largeur de la fosse augmente \u00e0 950 mm. La semi surbaiss\u00e9e Manoovr avec fosse pour bras de pelle est disponible avec des distances entre essieux de 1360 ou 1510 mm.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb16952&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb onclick=\u00a0\u00bblink_image\u00a0\u00bb css_animation=\u00a0\u00bbright-to-left\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>Les avantages de la Manoovr<\/h2>\n<p>Avec la technologie Manoovr, Nooteboom offre de nombreux avantages qui ne sont pas affect\u00e9s par l\u2019application d\u2019une fosse pour bras de pelle. En comparaison avec d\u2019autres marques, la semi surbaiss\u00e9e Manoovr de Nooteboom a des avantages importants et uniques tels que\u00a0: une hauteur de plateau de 780 mm, une course de suspension de 500 mm, 60 degr\u00e9s d\u2019angle de braquage, des pneus pouvant rouler 300 000 km et 12 tonnes par essieu en Europe. Le r\u00e9sultat\u00a0: faibles co\u00fbts de pneus et d\u2019entretien ainsi qu\u2019une valeur r\u00e9siduelle \u00e9lev\u00e9e. Combin\u00e9e avec des rampes en aluminium ou hydrauliques la Manoovr avec fosse pour bras de pelle est la remorque multifonction id\u00e9ale pour le transport de machines.[\/vc_column_text][vc_single_image image=\u00a0\u00bb16958&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_message message_box_color=\u00a0\u00bbgrey\u00a0\u00bb]<\/p>\n<p class=\"nospacing1\" style=\"line-height: 115%;\"><span style=\"font-family: 'Arial',sans-serif;\">Nooteboom d\u00e9veloppe rapidement les nouvelles versions et des options pour la g\u00e9n\u00e9ration Manoovr. La version avec une fosse pour bras de pelle a \u00e9t\u00e9 command\u00e9e discr\u00e8tement par plusieurs op\u00e9rateurs de transport et les premi\u00e8res seront bient\u00f4t mises en service par Van der Vlist. De nombreux conducteurs appr\u00e9cieront \u00e9galement la fosse pour bras de pelle parce que c\u2019est un endroit id\u00e9al pour ranger les cha\u00eenes et les cales de roue. Et c\u2019est un bonus suppl\u00e9mentaire (non n\u00e9gligeable).\u00a0<\/span><\/p>\n<p><a class=\"button\" href=\"https:\/\/www.nooteboom.com\/fr\/trailers\/surbaissee-avec-essieux-pendulaires\/\">En savoir plus sur les avantages MANOOVR MPL<\/a>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse. La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu&rsquo;\u00e0 six essieux.","protected":false},"author":45,"featured_media":16954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-17130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v25.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nouvelle Manoovr avec fosse pour bras de pelle | Nooteboom Trailers<\/title>\n<meta name=\"description\" content=\"En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse. La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu&#039;\u00e0 six essieux. | Nooteboom Trailers\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle Manoovr avec fosse pour bras de pelle\" \/>\n<meta property=\"og:description\" content=\"En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse. La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu&#039;\u00e0 six essieux. | Nooteboom Trailers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Nooteboom Trailers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/nl-nl.facebook.com\/nooteboomtrailers\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-29T06:38:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-29T06:38:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"972\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Xander Kamphuis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Xander Kamphuis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/\"},\"author\":{\"name\":\"Xander Kamphuis\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#\/schema\/person\/375b5d0caf72eccb8a568826d6390b66\"},\"headline\":\"Nouvelle Manoovr avec fosse pour bras de pelle\",\"datePublished\":\"2016-09-29T06:38:11+00:00\",\"dateModified\":\"2016-09-29T06:38:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/\"},\"wordCount\":515,\"publisher\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/\",\"url\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/\",\"name\":\"Nouvelle Manoovr avec fosse pour bras de pelle | Nooteboom Trailers\",\"isPartOf\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg\",\"datePublished\":\"2016-09-29T06:38:11+00:00\",\"dateModified\":\"2016-09-29T06:38:31+00:00\",\"description\":\"En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse. La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu'\u00e0 six essieux. | Nooteboom Trailers\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage\",\"url\":\"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg\",\"contentUrl\":\"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg\",\"width\":2048,\"height\":972},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nooteboom.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelle Manoovr avec fosse pour bras de pelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#website\",\"url\":\"https:\/\/www.nooteboom.com\/fr\/\",\"name\":\"Nooteboom Trailers\",\"description\":\"Gets you there.\",\"publisher\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nooteboom.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#organization\",\"name\":\"Nooteboom Trailers\",\"url\":\"https:\/\/www.nooteboom.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.nooteboom.com\/wp-content\/uploads\/logo.png\",\"contentUrl\":\"https:\/\/www.nooteboom.com\/wp-content\/uploads\/logo.png\",\"width\":111,\"height\":66,\"caption\":\"Nooteboom Trailers\"},\"image\":{\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/nl-nl.facebook.com\/nooteboomtrailers\/\",\"https:\/\/nl.linkedin.com\/company\/nooteboom-trailers\",\"https:\/\/www.youtube.com\/user\/Nooteboomtrailers\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#\/schema\/person\/375b5d0caf72eccb8a568826d6390b66\",\"name\":\"Xander Kamphuis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nooteboom.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a65af99837c9e097867d15cf2c32d9c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a65af99837c9e097867d15cf2c32d9c4?s=96&d=mm&r=g\",\"caption\":\"Xander Kamphuis\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nouvelle Manoovr avec fosse pour bras de pelle | Nooteboom Trailers","description":"En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse. La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu'\u00e0 six essieux. | Nooteboom Trailers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelle Manoovr avec fosse pour bras de pelle","og_description":"En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse. La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu'\u00e0 six essieux. | Nooteboom Trailers","og_url":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/","og_site_name":"Nooteboom Trailers","article_publisher":"https:\/\/nl-nl.facebook.com\/nooteboomtrailers\/","article_published_time":"2016-09-29T06:38:11+00:00","article_modified_time":"2016-09-29T06:38:31+00:00","og_image":[{"width":2048,"height":972,"url":"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg","type":"image\/jpeg"}],"author":"Xander Kamphuis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Xander Kamphuis","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#article","isPartOf":{"@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/"},"author":{"name":"Xander Kamphuis","@id":"https:\/\/www.nooteboom.com\/fr\/#\/schema\/person\/375b5d0caf72eccb8a568826d6390b66"},"headline":"Nouvelle Manoovr avec fosse pour bras de pelle","datePublished":"2016-09-29T06:38:11+00:00","dateModified":"2016-09-29T06:38:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/"},"wordCount":515,"publisher":{"@id":"https:\/\/www.nooteboom.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/","url":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/","name":"Nouvelle Manoovr avec fosse pour bras de pelle | Nooteboom Trailers","isPartOf":{"@id":"https:\/\/www.nooteboom.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage"},"image":{"@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg","datePublished":"2016-09-29T06:38:11+00:00","dateModified":"2016-09-29T06:38:31+00:00","description":"En l\u2019espace d\u2019un an la technologie de la Manoovr de Nooteboom est devenue un mot familier dans le monde du transport international exceptionnel. La derni\u00e8re innovation dans le programme Manoovr est une version avec une fosse pour bras de pelle. Cette option rend la semi surbaiss\u00e9e encore plus polyvalente, surtout pour le transport de pelles excavatrices ou les engins de d\u00e9molition car le bras articul\u00e9 peut \u00eatre positionn\u00e9 dans la fosse. La fosse \u00e0 bras de pelle est disponible en s\u00e9rie sur toutes les semi surbaiss\u00e9es, de la g\u00e9n\u00e9ration Manoovr qui ont jusqu'\u00e0 six essieux. | Nooteboom Trailers","breadcrumb":{"@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#primaryimage","url":"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg","contentUrl":"https:\/\/www.nooteboom.com\/wp-content\/uploads\/HR_Nooteboom.jpg","width":2048,"height":972},{"@type":"BreadcrumbList","@id":"https:\/\/www.nooteboom.com\/fr\/nouvelle-manoovr-avec-fosse-pour-bras-de-pelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nooteboom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelle Manoovr avec fosse pour bras de pelle"}]},{"@type":"WebSite","@id":"https:\/\/www.nooteboom.com\/fr\/#website","url":"https:\/\/www.nooteboom.com\/fr\/","name":"Nooteboom Trailers","description":"Gets you there.","publisher":{"@id":"https:\/\/www.nooteboom.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nooteboom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.nooteboom.com\/fr\/#organization","name":"Nooteboom Trailers","url":"https:\/\/www.nooteboom.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nooteboom.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.nooteboom.com\/wp-content\/uploads\/logo.png","contentUrl":"https:\/\/www.nooteboom.com\/wp-content\/uploads\/logo.png","width":111,"height":66,"caption":"Nooteboom Trailers"},"image":{"@id":"https:\/\/www.nooteboom.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/nl-nl.facebook.com\/nooteboomtrailers\/","https:\/\/nl.linkedin.com\/company\/nooteboom-trailers","https:\/\/www.youtube.com\/user\/Nooteboomtrailers"]},{"@type":"Person","@id":"https:\/\/www.nooteboom.com\/fr\/#\/schema\/person\/375b5d0caf72eccb8a568826d6390b66","name":"Xander Kamphuis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nooteboom.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a65af99837c9e097867d15cf2c32d9c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a65af99837c9e097867d15cf2c32d9c4?s=96&d=mm&r=g","caption":"Xander Kamphuis"}}]}},"_links":{"self":[{"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/posts\/17130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/comments?post=17130"}],"version-history":[{"count":5,"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/posts\/17130\/revisions"}],"predecessor-version":[{"id":17135,"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/posts\/17130\/revisions\/17135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/media\/16954"}],"wp:attachment":[{"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/media?parent=17130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/categories?post=17130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nooteboom.com\/fr\/wp-json\/wp\/v2\/tags?post=17130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}